{"id":578,"date":"2018-10-01T17:17:06","date_gmt":"2018-10-01T17:17:06","guid":{"rendered":"https:\/\/www.helios-tinting.com\/\/?p=578"},"modified":"2025-02-26T08:51:38","modified_gmt":"2025-02-26T08:51:38","slug":"pravno-obvestilo","status":"publish","type":"post","link":"https:\/\/www.helios-tinting.com\/sl\/pravno\/pravno-obvestilo\/","title":{"rendered":"Pravno obvestilo"},"content":{"rendered":"<p>Na spletnih straneh predstavljamo splo\u0161ne informacije o dru\u017ebi Helios TBLUS d.o.o. in z<a href=\"https:\/\/www.helios-tinting.com\/wp-content\/uploads\/2025\/02\/Pravno-obvestilo.pdf\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-490 size-full\" src=\"https:\/\/www.helios-tinting.com\/\/wp-content\/uploads\/2018\/06\/pdf-ico.png\" alt=\"\" width=\"70\" height=\"70\" \/><\/a> njo povezanimi dru\u017ebami, o poslovanju teh dru\u017eb in njihovih proizvodih. Prosimo vas, da natan\u010dno preberete to obvestilo, ki velja za vsakogar, ki obi\u0161\u010de to spletno stran. Z uporabo spletne strani https:\/\/www.helios-tinting.com\/ uporabnik potrjuje, da je sprejel tu opisane pogoje in se z njimi strinja.<\/p>\n<p><strong><a href=\"https:\/\/www.helios-tinting.com\/\/legal\/splosni-pogoji-poslovanja\/\">Splo\u0161ni pogoji poslovanja podjetja<\/a><\/strong><\/p>\n<p><strong>Osebna izkaznica<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td>Podjetje:<\/td>\n<td>KANSAI HELIOS Slovenija<\/td>\n<\/tr>\n<tr>\n<td>Mati\u010dna \u0161tevilka:<\/td>\n<td>5043212000<\/td>\n<\/tr>\n<tr>\n<td>Dav\u010dna \u0161tevilka:<\/td>\n<td>SI 45984794<\/td>\n<\/tr>\n<tr>\n<td>Vlo\u017ena \u0161tevilka:<\/td>\n<td>10447300, Sodni register, Okro\u017eno sodi\u0161\u010de v Ljubljani<\/td>\n<\/tr>\n<tr>\n<td>Sede\u017e:<\/td>\n<td>Koli\u010devo<\/td>\n<\/tr>\n<tr>\n<td>Poslovni naslov:<\/td>\n<td>Koli\u010devo 65, 1230 Dom\u017eale<\/td>\n<\/tr>\n<tr>\n<td>Telefon:<\/td>\n<td>+386 1\/722 40 00<\/td>\n<\/tr>\n<tr>\n<td>Fax:<\/td>\n<td>+386 1\/722 41 10<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-961\" src=\"https:\/\/www.helios-tinting.com\/wp-content\/uploads\/2021\/09\/Legal-notice-Logoline-RGB.svg\" alt=\"\" width=\"300\" height=\"21\" \/><\/p>\n<p><strong>Pravne informacije<\/strong><\/p>\n<p>Vse pravice so pridr\u017eane. Obvestilo se nana\u0161a na za\u010detno stran in vse podstrani spletnega mesta https:\/\/www.helios-tinting.com\/. Vse informacije in gradiva (pisna in slikovna) na spletnem mestu https:\/\/www.helios-tinting.com\/ so za\u0161\u010ditena z avtorsko in sorodnimi pravicami in\/ali s pravicami industrijske lastnine, katerih imetnica je dru\u017eba KANSAI HELIOS Slovenija in\/ali z njo povezane dru\u017ebe. Uporabnik lahko uporablja vsebine na spletnem mestu https:\/\/www.helios-tinting.com\/ izklju\u010dno za svojo osebno, nekomercialno rabo. Prepovedana je vsaka druga oblika uporabe vsebin spletne strani https:\/\/www.helios-tinting.com\/, predvsem za komercialne namene.<\/p>\n<p><strong>Omejitev uporabe informacij in gradiv<\/strong><\/p>\n<p>Vse informacije in gradiva (pisna in slikovna), objavljena na spletni strani https:\/\/www.helios-tinting.com\/, se lahko reproducira le v nekomercialne namene, pri \u010demer se morajo ohraniti vsa navedena opozorila o avtorski in sorodnih pravicah in\/ali pravicah industrijske lastnine. Teh informacij in gradiv se ne sme prepisovati, razmno\u017eevati ali kako druga\u010de raz\u0161irjati v komercialne namene brez izrecnega pisnega dovoljenja KANSAI HELIOS Slovenija in\/ali z njo povezanih dru\u017eb.<\/p>\n<p>Na vsaki reprodukciji ali primerku vsebine iz te spletne strani mora biti uporabljen znak KANSAI HELIOS Slovenija, v skladu s pravili celostne grafi\u010dne podobe \u2013 vse pravice pridr\u017eane. Spletno mesto https:\/\/www.helios-tinting.com\/ vsebuje tudi informacije tretjih oseb in povezave s spletnimi stranmi tretjih oseb, pri \u010demer dru\u017eba KANSAI HELIOS Slovenija ni odgovorna za njihovo vsebino in v zvezi s tem ne daje nobenih jamstev. Pri obisku in uporabi povezanih spletnih strani je odgovornost dru\u017ebe KANSAI HELIOS Slovenija v celoti izklju\u010dena.<\/p>\n<p>To pravno obvestilo lahko dru\u017eba KANSAI HELIOS Slovenija kadarkoli spremeni in je za uporabnike zavezujo\u010de v vsakokrat veljavni obliki, zato je priporo\u010deno, da se uporabniki natan\u010dno seznanijo z njegovo vsebino ob vsakem obisku spletne strani https:\/\/www.helios-tinting.com\/. Uporaba spletne strani https:\/\/www.helios-tinting.com\/ v nasprotju s tukaj navedenimi pravili je prepovedana. Uporabnik, ki uporablja spletno stran https:\/\/www.helios-tinting.com\/ v nasprotju s tukaj navedenimi pravili, je v celoti sam odgovoren za svoja ravnanja.<\/p>\n<p><strong>Omejitev odgovornosti<\/strong><\/p>\n<p>Vse informacije in gradiva na spletni strani https:\/\/www.helios-tinting.com\/ so informativne narave. Dru\u017eba KANSAI HELIOS Slovenija se trudi za pravilnost, a\u017eurnost in popolnost podatkov na spletni strani https:\/\/www.helios-tinting.com\/, vendar ne more jam\u010diti za njihovo to\u010dnost in celovitost ter v zvezi s tem ne prevzema nikakr\u0161ne odgovornosti.<\/p>\n<p>Uporabniki uporabljajo spletno stran https:\/\/www.helios-tinting.com\/ in na tej strani objavljene vsebine na lastno odgovornost. Niti dru\u017eba KANSAI HELIOS Slovenija, niti katerakoli pravna ali fizi\u010dna oseba, ki je sodelovala pri nastanku in izdelavi spletne strani ali \u0161e sodeluje pri nadgradnjah, zato ne odgovarja za nobeno \u0161kodo, ki bi izhajala iz dostopa do, uporabe ali nezmo\u017enosti uporabe informacij na teh spletnih straneh ali za kakr\u0161nekoli napake ali pomanjkljivosti v njihovi vsebini.<\/p>\n<p>Dru\u017eba KANSAI HELIOS Slovenija ni odgovorna za \u0161kodo (vklju\u010dno za tisto, ki jih povzro\u010dijo virusi), ki bi jo zaradi obiska spletne strani https:\/\/www.helios-tinting.com\/ ali kakr\u0161nekoli njene uporabe uporabnik utrpel na ra\u010dunalni\u0161ki opremi, mobilnem telefonu ali katerekoli drugi napravi in\/ali aplikaciji, s katero je mogo\u010de dostopati do te spletne strani. Prav tako ni dru\u017eba KANSAI HELIOS Slovenija odgovorna za kakr\u0161nekoli drugo vrsto \u0161kode, ki bi utegnila nastati zaradi uporabe ali nezmo\u017enosti uporabe spletne strani https:\/\/www.helios-tinting.com\/ <a href=\"http:\/\/www.helios-deco.com\/\">.<\/a>\u00a0Dru\u017eba KANSAI HELIOS Slovenija si pridr\u017euje pravico, da spremeni vsebino spletne strani https:\/\/www.helios-tinting.com\/ kadarkoli, na kakr\u0161enkoli na\u010din in ne glede na razlog, brez predhodnega obvestila, ter ne prevzema nobene odgovornosti za kakr\u0161nekoli posledice takih sprememb.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na spletnih straneh predstavljamo splo\u0161ne informacije o dru\u017ebi Helios TBLUS d.o.o. in z njo povezanimi dru\u017ebami, o poslovanju teh dru\u017eb in njihovih proizvodih. Prosimo vas, da natan\u010dno preberete to obvestilo, ki velja za vsakogar, ki obi\u0161\u010de to spletno stran. Z uporabo spletne strani https:\/\/www.helios-tinting.com\/ uporabnik potrjuje, da je sprejel tu opisane pogoje in se z [&hellip;]<\/p>\n","protected":false},"author":312,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61],"tags":[],"class_list":["post-578","post","type-post","status-publish","format-standard","hentry","category-pravno"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pravno obvestilo - Helios Tinting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.helios-tinting.com\/sl\/pravno\/pravno-obvestilo\/\" \/>\n<meta property=\"og:locale\" content=\"sl_SI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pravno obvestilo - Helios Tinting\" \/>\n<meta property=\"og:description\" content=\"Na spletnih straneh predstavljamo splo\u0161ne informacije o dru\u017ebi Helios TBLUS d.o.o. in z njo povezanimi dru\u017ebami, o poslovanju teh dru\u017eb in njihovih proizvodih. Prosimo vas, da natan\u010dno preberete to obvestilo, ki velja za vsakogar, ki obi\u0161\u010de to spletno stran. Z uporabo spletne strani https:\/\/www.helios-tinting.com\/ uporabnik potrjuje, da je sprejel tu opisane pogoje in se z [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.helios-tinting.com\/sl\/pravno\/pravno-obvestilo\/\" \/>\n<meta property=\"og:site_name\" content=\"Helios Tinting\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-01T17:17:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-26T08:51:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.helios-tinting.com\/\/wp-content\/uploads\/2018\/06\/pdf-ico.png\" \/>\n<meta name=\"author\" content=\"BBH2cpggRkK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"BBH2cpggRkK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/pravno\\\/pravno-obvestilo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/pravno\\\/pravno-obvestilo\\\/\"},\"author\":{\"name\":\"BBH2cpggRkK\",\"@id\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/#\\\/schema\\\/person\\\/98dd2c90f3798762ed62937e8b44fc67\"},\"headline\":\"Pravno obvestilo\",\"datePublished\":\"2018-10-01T17:17:06+00:00\",\"dateModified\":\"2025-02-26T08:51:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/pravno\\\/pravno-obvestilo\\\/\"},\"wordCount\":726,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/pravno\\\/pravno-obvestilo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.helios-tinting.com\\\/\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/pdf-ico.png\",\"articleSection\":[\"Pravno\"],\"inLanguage\":\"sl-SI\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/pravno\\\/pravno-obvestilo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/pravno\\\/pravno-obvestilo\\\/\",\"url\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/pravno\\\/pravno-obvestilo\\\/\",\"name\":\"Pravno obvestilo - Helios Tinting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/pravno\\\/pravno-obvestilo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/pravno\\\/pravno-obvestilo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.helios-tinting.com\\\/\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/pdf-ico.png\",\"datePublished\":\"2018-10-01T17:17:06+00:00\",\"dateModified\":\"2025-02-26T08:51:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/pravno\\\/pravno-obvestilo\\\/#breadcrumb\"},\"inLanguage\":\"sl-SI\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/pravno\\\/pravno-obvestilo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sl-SI\",\"@id\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/pravno\\\/pravno-obvestilo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.helios-tinting.com\\\/\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/pdf-ico.png\",\"contentUrl\":\"https:\\\/\\\/www.helios-tinting.com\\\/\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/pdf-ico.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/pravno\\\/pravno-obvestilo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pravno obvestilo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/#website\",\"url\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/\",\"name\":\"Helios Tinting\",\"description\":\"World of perfect colors\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sl-SI\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/#organization\",\"name\":\"Helios Tinting\",\"url\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sl-SI\",\"@id\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.helios-tinting.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Helios-TINTING-logo-png24.png\",\"contentUrl\":\"https:\\\/\\\/www.helios-tinting.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Helios-TINTING-logo-png24.png\",\"width\":1024,\"height\":164,\"caption\":\"Helios Tinting\"},\"image\":{\"@id\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.helios-tinting.com\\\/sl\\\/#\\\/schema\\\/person\\\/98dd2c90f3798762ed62937e8b44fc67\",\"name\":\"BBH2cpggRkK\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sl-SI\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d97b37048d9dc3177a74101b65b7fc8246236775582c4d0671f2bab0da901c24?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d97b37048d9dc3177a74101b65b7fc8246236775582c4d0671f2bab0da901c24?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d97b37048d9dc3177a74101b65b7fc8246236775582c4d0671f2bab0da901c24?s=96&d=mm&r=g\",\"caption\":\"BBH2cpggRkK\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pravno obvestilo - Helios Tinting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.helios-tinting.com\/sl\/pravno\/pravno-obvestilo\/","og_locale":"sl_SI","og_type":"article","og_title":"Pravno obvestilo - Helios Tinting","og_description":"Na spletnih straneh predstavljamo splo\u0161ne informacije o dru\u017ebi Helios TBLUS d.o.o. in z njo povezanimi dru\u017ebami, o poslovanju teh dru\u017eb in njihovih proizvodih. Prosimo vas, da natan\u010dno preberete to obvestilo, ki velja za vsakogar, ki obi\u0161\u010de to spletno stran. Z uporabo spletne strani https:\/\/www.helios-tinting.com\/ uporabnik potrjuje, da je sprejel tu opisane pogoje in se z [&hellip;]","og_url":"https:\/\/www.helios-tinting.com\/sl\/pravno\/pravno-obvestilo\/","og_site_name":"Helios Tinting","article_published_time":"2018-10-01T17:17:06+00:00","article_modified_time":"2025-02-26T08:51:38+00:00","og_image":[{"url":"https:\/\/www.helios-tinting.com\/\/wp-content\/uploads\/2018\/06\/pdf-ico.png","type":"","width":"","height":""}],"author":"BBH2cpggRkK","twitter_card":"summary_large_image","twitter_misc":{"Written by":"BBH2cpggRkK","Est. reading time":"4 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.helios-tinting.com\/sl\/pravno\/pravno-obvestilo\/#article","isPartOf":{"@id":"https:\/\/www.helios-tinting.com\/sl\/pravno\/pravno-obvestilo\/"},"author":{"name":"BBH2cpggRkK","@id":"https:\/\/www.helios-tinting.com\/sl\/#\/schema\/person\/98dd2c90f3798762ed62937e8b44fc67"},"headline":"Pravno obvestilo","datePublished":"2018-10-01T17:17:06+00:00","dateModified":"2025-02-26T08:51:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.helios-tinting.com\/sl\/pravno\/pravno-obvestilo\/"},"wordCount":726,"commentCount":0,"publisher":{"@id":"https:\/\/www.helios-tinting.com\/sl\/#organization"},"image":{"@id":"https:\/\/www.helios-tinting.com\/sl\/pravno\/pravno-obvestilo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.helios-tinting.com\/\/wp-content\/uploads\/2018\/06\/pdf-ico.png","articleSection":["Pravno"],"inLanguage":"sl-SI","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.helios-tinting.com\/sl\/pravno\/pravno-obvestilo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.helios-tinting.com\/sl\/pravno\/pravno-obvestilo\/","url":"https:\/\/www.helios-tinting.com\/sl\/pravno\/pravno-obvestilo\/","name":"Pravno obvestilo - Helios Tinting","isPartOf":{"@id":"https:\/\/www.helios-tinting.com\/sl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.helios-tinting.com\/sl\/pravno\/pravno-obvestilo\/#primaryimage"},"image":{"@id":"https:\/\/www.helios-tinting.com\/sl\/pravno\/pravno-obvestilo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.helios-tinting.com\/\/wp-content\/uploads\/2018\/06\/pdf-ico.png","datePublished":"2018-10-01T17:17:06+00:00","dateModified":"2025-02-26T08:51:38+00:00","breadcrumb":{"@id":"https:\/\/www.helios-tinting.com\/sl\/pravno\/pravno-obvestilo\/#breadcrumb"},"inLanguage":"sl-SI","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.helios-tinting.com\/sl\/pravno\/pravno-obvestilo\/"]}]},{"@type":"ImageObject","inLanguage":"sl-SI","@id":"https:\/\/www.helios-tinting.com\/sl\/pravno\/pravno-obvestilo\/#primaryimage","url":"https:\/\/www.helios-tinting.com\/\/wp-content\/uploads\/2018\/06\/pdf-ico.png","contentUrl":"https:\/\/www.helios-tinting.com\/\/wp-content\/uploads\/2018\/06\/pdf-ico.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.helios-tinting.com\/sl\/pravno\/pravno-obvestilo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.helios-tinting.com\/sl\/"},{"@type":"ListItem","position":2,"name":"Pravno obvestilo"}]},{"@type":"WebSite","@id":"https:\/\/www.helios-tinting.com\/sl\/#website","url":"https:\/\/www.helios-tinting.com\/sl\/","name":"Helios Tinting","description":"World of perfect colors","publisher":{"@id":"https:\/\/www.helios-tinting.com\/sl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.helios-tinting.com\/sl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sl-SI"},{"@type":"Organization","@id":"https:\/\/www.helios-tinting.com\/sl\/#organization","name":"Helios Tinting","url":"https:\/\/www.helios-tinting.com\/sl\/","logo":{"@type":"ImageObject","inLanguage":"sl-SI","@id":"https:\/\/www.helios-tinting.com\/sl\/#\/schema\/logo\/image\/","url":"https:\/\/www.helios-tinting.com\/wp-content\/uploads\/2019\/01\/Helios-TINTING-logo-png24.png","contentUrl":"https:\/\/www.helios-tinting.com\/wp-content\/uploads\/2019\/01\/Helios-TINTING-logo-png24.png","width":1024,"height":164,"caption":"Helios Tinting"},"image":{"@id":"https:\/\/www.helios-tinting.com\/sl\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.helios-tinting.com\/sl\/#\/schema\/person\/98dd2c90f3798762ed62937e8b44fc67","name":"BBH2cpggRkK","image":{"@type":"ImageObject","inLanguage":"sl-SI","@id":"https:\/\/secure.gravatar.com\/avatar\/d97b37048d9dc3177a74101b65b7fc8246236775582c4d0671f2bab0da901c24?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d97b37048d9dc3177a74101b65b7fc8246236775582c4d0671f2bab0da901c24?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d97b37048d9dc3177a74101b65b7fc8246236775582c4d0671f2bab0da901c24?s=96&d=mm&r=g","caption":"BBH2cpggRkK"}}]}},"_links":{"self":[{"href":"https:\/\/www.helios-tinting.com\/sl\/wp-json\/wp\/v2\/posts\/578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.helios-tinting.com\/sl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.helios-tinting.com\/sl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.helios-tinting.com\/sl\/wp-json\/wp\/v2\/users\/312"}],"replies":[{"embeddable":true,"href":"https:\/\/www.helios-tinting.com\/sl\/wp-json\/wp\/v2\/comments?post=578"}],"version-history":[{"count":13,"href":"https:\/\/www.helios-tinting.com\/sl\/wp-json\/wp\/v2\/posts\/578\/revisions"}],"predecessor-version":[{"id":1793,"href":"https:\/\/www.helios-tinting.com\/sl\/wp-json\/wp\/v2\/posts\/578\/revisions\/1793"}],"wp:attachment":[{"href":"https:\/\/www.helios-tinting.com\/sl\/wp-json\/wp\/v2\/media?parent=578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.helios-tinting.com\/sl\/wp-json\/wp\/v2\/categories?post=578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.helios-tinting.com\/sl\/wp-json\/wp\/v2\/tags?post=578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}